{"id":2160,"date":"2023-12-07T15:35:41","date_gmt":"2023-12-07T15:35:41","guid":{"rendered":"https:\/\/flg.dotflorence.com\/tours\/passeggiata-a-firenze\/"},"modified":"2024-10-17T17:03:52","modified_gmt":"2024-10-17T17:03:52","slug":"passeggiata-a-firenze-david","status":"publish","type":"tours","link":"https:\/\/florencelocalguides.com\/it\/tours\/passeggiata-a-firenze-david\/","title":{"rendered":"Passeggiata a Firenze e David di Michelangelo"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Tour privato con il David, il Duomo e Ponte Vecchio: le tappe imperdibili della citt\u00e0 <\/h2>\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Siete a Firenze per la prima volta e volete ammirare i suoi capolavori in tre ore con una guida privata?\u00a0<\/span>&#13;\n&#13;\n<span style=\"font-weight: 400;\">Oppure questa non \u00e8 la vostra prima visita in citt\u00e0, ma volete approfondire i suoi tesori con l&#8217;aiuto di un esperto? <\/span><\/p>\n\n<h3 class=\"wp-block-heading\">Questo \u00e8 il giro citt\u00e0 a piedi perfetto per voi!<\/h3>\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Visiterete le tappe imperdibili di Firenze, e allo stesso tempo scoprirete i suoi angoli nascosti. Una passeggiata piacevole che vi far\u00e0 conoscere il <\/span><i><span style=\"font-weight: 400;\">David<\/span><\/i><span style=\"font-weight: 400;\"> di Michelangelo, durante la quale parlerete di storia e ammirerete lo splendore del <\/span><b>Rinascimento<\/b><span style=\"font-weight: 400;\">, divertendovi con una vera esperta del territorio.\u00a0<\/span>&#13;\n&#13;\n\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Volete modificare l\u2019itinerario? Fatecelo sapere e creeremo l\u2019esperienza personalizzata perfetta per voi!<\/span><\/p>\n\n<h2 class=\"wp-block-heading\">Michelangelo e David alla Galleria dell\u2019Accademia<\/h2>\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">La visita comincia con una delle opere d\u2019arte pi\u00f9 famose del mondo: il David di Michelangelo. Entrerete alla Galleria grazie ad un accesso prioritario, saltando le lunghe code di visitatori che arrivano da ogni parte del mondo per ammirare questo incredibile marmo! Parlare del David significa anche parlare di Michelangelo, scoprendo la sua lunga e tormentata esistenza. La Galleria dell\u2019Accademia ospita altri capolavori del maestro come i Prigioni, opere non finite, meno conosciute dal grande pubblico ma altrettanto potenti ed evocative.<\/span><\/p>\n\n<h2 class=\"wp-block-heading\">Piazza del Duomo e il complesso della Cattedrale<\/h2>\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">La visita guidata prosegue in direzione della <strong>Cattedrale di Firenze<\/strong>. Costruita per mostrare il potere e il benessere della citt\u00e0, il <strong>Duomo di Santa Maria del Fiore<\/strong> era la chiesa cristiana pi\u00f9 grande del Rinascimento. Ai piedi della cupola, la guida vi sveler\u00e0 i segreti della sua costruzione e della brillante intelligenza del suo ideatore, <a href=\"https:\/\/it.wikipedia.org\/wiki\/Filippo_Brunelleschi\" target=\"_blank\" rel=\"noopener\"><strong>Filippo Brunelleschi<\/strong><\/a>. Lo sapevate che la pi\u00f9 impressionante cupola del Quattrocento \u00e8 ancora oggi <strong>la pi\u00f9 ampia mai costruita in mattoni e senza un\u2019impalcatura<\/strong>? Queste sono solo alcune delle ragioni per le quali l\u2019opera di Brunelleschi affascina ancora oggi chi la osserva. In questa visita capirete come, 600 anni fa, Filippo Brunelleschi da semplice orafo divenne l&#8217;architetto pi\u00f9 ammirato del suo tempo.<\/span><\/p>\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Vorreste entrare in Duomo da un accesso riservato? Fatecelo sapere e vi organizzeremo una visita speciale saltando le lunghe file.<\/span><\/p>\n\n<h2 class=\"wp-block-heading\">Passeggiando nella Firenze medievale fino a piazza della Signoria<\/h2>\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Camminando fra i monumenti del centro religioso, attraverserete il quartiere medievale per raggiungere il cuore politico di Firenze: piazza della Signoria, un vero e proprio museo a cielo aperto. Le statue che vi circondano hanno molte storie da raccontare e la vostra guida vi aiuter\u00e0 a sentire le loro voci!<\/span><\/p>\n\n<h2 class=\"wp-block-heading\">Ponte Vecchio e i suoi orafi luccicanti<\/h2>\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">A pochi passi dalla piazza ecco un altro simbolo di Firenze: il Ponte Vecchio. La visita guidata finir\u00e0 qui, circondati dalle famose botteghe degli orafi e dall\u2019atmosfera magica di un luogo antico di secoli.<\/span><\/p>\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Volete continuare questa esperienza unica <a href=\"https:\/\/florencelocalguides.com\/it\/tours\/tour-guidato-uffizi-senza-stress\/\" target=\"_blank\" rel=\"noopener\"><strong>visitando la Galleria degli Uffizi<\/strong><\/a>? Possiamo organizzare la visita privata al Museo per voi.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il tour perfetto per scoprire Firenze a piedi, grazie ad una piacevole passeggiata di tre ore. Visiterete i monumenti imperdibili, compreso il David di Michelangelo, piazza del Duomo e Ponte Vecchio, e allo stesso tempo scoprirete alcuni angoli nascosti della citt\u00e0. Volete modificare l\u2019itinerario? Fatecelo sapere e creeremo l\u2019esperienza personalizzata perfetta per voi!<\/p>\n","protected":false},"author":1,"featured_media":1729,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"tours_category":[],"tours_tag":[],"class_list":["post-2160","tours","type-tours","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Passeggiata a Firenze - Florence Local Experts<\/title>\n<meta name=\"description\" content=\"Tour privato con il David, il Duomo e Ponte Vecchio: le tappe imperdibili della citt\u00e0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/florencelocalguides.com\/it\/tours\/passeggiata-a-firenze-david\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Passeggiata a Firenze - Florence Local Experts\" \/>\n<meta property=\"og:description\" content=\"Tour privato con il David, il Duomo e Ponte Vecchio: le tappe imperdibili della citt\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/florencelocalguides.com\/it\/tours\/passeggiata-a-firenze-david\/\" \/>\n<meta property=\"og:site_name\" content=\"Florence Local Experts\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-17T17:03:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/florencelocalguides.com\/wp-content\/uploads\/walking-tour\/copia-di-copertina.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Passeggiata a Firenze - Florence Local Experts","description":"Tour privato con il David, il Duomo e Ponte Vecchio: le tappe imperdibili della citt\u00e0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/florencelocalguides.com\/it\/tours\/passeggiata-a-firenze-david\/","og_locale":"it_IT","og_type":"article","og_title":"Passeggiata a Firenze - Florence Local Experts","og_description":"Tour privato con il David, il Duomo e Ponte Vecchio: le tappe imperdibili della citt\u00e0.","og_url":"https:\/\/florencelocalguides.com\/it\/tours\/passeggiata-a-firenze-david\/","og_site_name":"Florence Local Experts","article_modified_time":"2024-10-17T17:03:52+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/florencelocalguides.com\/wp-content\/uploads\/walking-tour\/copia-di-copertina.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/florencelocalguides.com\/it\/tours\/passeggiata-a-firenze-david\/","url":"https:\/\/florencelocalguides.com\/it\/tours\/passeggiata-a-firenze-david\/","name":"Passeggiata a Firenze - Florence Local Experts","isPartOf":{"@id":"https:\/\/florencelocalguides.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/florencelocalguides.com\/it\/tours\/passeggiata-a-firenze-david\/#primaryimage"},"image":{"@id":"https:\/\/florencelocalguides.com\/it\/tours\/passeggiata-a-firenze-david\/#primaryimage"},"thumbnailUrl":"https:\/\/florencelocalguides.com\/wp-content\/uploads\/walking-tour\/copia-di-copertina.jpeg","datePublished":"2023-12-07T15:35:41+00:00","dateModified":"2024-10-17T17:03:52+00:00","description":"Tour privato con il David, il Duomo e Ponte Vecchio: le tappe imperdibili della citt\u00e0.","breadcrumb":{"@id":"https:\/\/florencelocalguides.com\/it\/tours\/passeggiata-a-firenze-david\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/florencelocalguides.com\/it\/tours\/passeggiata-a-firenze-david\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/florencelocalguides.com\/it\/tours\/passeggiata-a-firenze-david\/#primaryimage","url":"https:\/\/florencelocalguides.com\/wp-content\/uploads\/walking-tour\/copia-di-copertina.jpeg","contentUrl":"https:\/\/florencelocalguides.com\/wp-content\/uploads\/walking-tour\/copia-di-copertina.jpeg","width":1920,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/florencelocalguides.com\/it\/tours\/passeggiata-a-firenze-david\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/florencelocalguides.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tours","item":"https:\/\/florencelocalguides.com\/it\/tours\/"},{"@type":"ListItem","position":3,"name":"Passeggiata a Firenze e David di Michelangelo"}]},{"@type":"WebSite","@id":"https:\/\/florencelocalguides.com\/it\/#website","url":"https:\/\/florencelocalguides.com\/it\/","name":"Florence Local Experts","description":"","publisher":{"@id":"https:\/\/florencelocalguides.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/florencelocalguides.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/florencelocalguides.com\/it\/#organization","name":"Florence Local Experts","url":"https:\/\/florencelocalguides.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/florencelocalguides.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/florencelocalguides.com\/wp-content\/uploads\/logo\/logo-floe-ok.svg","contentUrl":"https:\/\/florencelocalguides.com\/wp-content\/uploads\/logo\/logo-floe-ok.svg","caption":"Florence Local Experts"},"image":{"@id":"https:\/\/florencelocalguides.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/tours\/2160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/tours"}],"about":[{"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/types\/tours"}],"author":[{"embeddable":true,"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/comments?post=2160"}],"version-history":[{"count":10,"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/tours\/2160\/revisions"}],"predecessor-version":[{"id":3889,"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/tours\/2160\/revisions\/3889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/media\/1729"}],"wp:attachment":[{"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/media?parent=2160"}],"wp:term":[{"taxonomy":"tours_category","embeddable":true,"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/tours_category?post=2160"},{"taxonomy":"tours_tag","embeddable":true,"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/tours_tag?post=2160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}