{"id":2242,"date":"2023-12-07T15:35:20","date_gmt":"2023-12-07T15:35:20","guid":{"rendered":"https:\/\/flg.dotflorence.com\/tours\/il-lato-oscuro-di-firenze-una-passeggiata-misteriosa-ed-intrigante\/"},"modified":"2024-03-19T12:41:36","modified_gmt":"2024-03-19T12:41:36","slug":"tour-firenze-misteriosa-ed-intrigante","status":"publish","type":"tours","link":"https:\/\/florencelocalguides.com\/it\/tours\/tour-firenze-misteriosa-ed-intrigante\/","title":{"rendered":"Il lato oscuro di Firenze: una passeggiata misteriosa ed intrigante"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Un itinerario guidato privato per scoprire passione e sangue della culla del Rinascimento<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Firenze, celebrata nel mondo per il suo splendore rinascimentale, nasconde un passato ai pi\u00f9 sconosciuto, un<strong> lato proibito<\/strong> che la rese famosa fra i <strong>peccatori impenitenti del XV secolo<\/strong>. Oltre ad amori proibiti, la citt\u00e0 \u00e8 stata lo scenario di efferati <strong>assassinii<\/strong>, strazianti <strong>torture<\/strong> e spietate <strong>esecuzioni<\/strong><\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">In questa visita di due ore una guida esperta vi porter\u00e0 indietro nel tempo, nei <strong>momenti pi\u00f9 cupi del Medioevo e del Rinascimento<\/strong>, mostrandovi i luoghi principali di Firenze, da <a href=\"\/it\/tours\/tour-privato-di-palazzo-pitti-e-giardino-di-boboli\/\"><strong>pia<\/strong><\/a><a href=\"https:\/\/florencelocalguides.com\/it\/tours\/tour-privato-di-palazzo-pitti-e-giardino-di-boboli\/\"><strong>zza Pitti<\/strong><\/a> a <strong>piazza della Signoria<\/strong>, e tesori meno conosciuti. Scoprirete come anche il presente abbia purtroppo molte storie tristi da raccontare.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L\u2019ultimo Medici: Gian Gastone<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La vostra passeggiata calcher\u00e0 questi sentieri incerti partendo da piazza Pitti, di fronte a quella che fu la reggia cittadina della <span style=\"font-weight: 400;\"><a href=\"\/it\/tours\/tour-famiglia-medici-a-firenze\/\"><strong>famiglia Medici<\/strong><\/a><\/span>. Qui l\u2019ultimo erede del <strong>Granducato di Toscana<\/strong>, Gian Gastone, pass\u00f2 i suoi giorni in completo libertinaggio, dando sfogo a vizi e desideri che lo portarono alla morte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Lutti misteriosi nella Firenze del Rinascimento<span style=\"font-weight: 400;\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il tour guidato continua verso quello che fu il palazzo di <span style=\"font-weight: 400;\"><strong><a href=\"https:\/\/it.wikipedia.org\/wiki\/Bianca_Cappello\" target=\"_blank\" rel=\"noreferrer noopener\">Bianca Cappello<\/a><\/strong><\/span>. A pochi passi dalla sua residenza privata, il <strong>Granduca Francesco I<\/strong> fece costruire un edificio facilmente distinguibile, per dare ospitalit\u00e0 alla sua bella e tormentata amante, la veneziana Bianca Cappello. La storia ebbe un lieto fine? Certamente no. La vostra guida vi racconter\u00e0 ogni dettaglio della loro misteriosa scomparsa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Come uccidere un Medici: la congiura dei Pazzi<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Una volta arrivati in piazza <strong>Santa Trinita<\/strong>, il luogo dove hanno vissuto alcune fra le pi\u00f9 potenti famiglie fiorentine, vi addentrerete nei vicoli della Firenze del Medioevo, che vi condurranno ad una tappa imperdibile della citt\u00e0: la <strong>Cattedrale di Santa Maria del Fiore<\/strong>. <\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Potreste mai credere che perfino la chiesa principale di Firenze \u00e8 stata lo scenario di <strong>una delle pi\u00f9 crudeli congiure del Rinascimento<\/strong>? Abbiamo gi\u00e0 detto come i Medici siano diventati i signori della citt\u00e0 nel XV secolo. Credete davvero che ognuno in citt\u00e0 fosse d\u2019accordo? La vostra guida risponder\u00e0 a questa e ad altre domande, raccontandovi come la <strong>famiglia Pazzi<\/strong> decise di ordire la loro congiura proprio all\u2019interno del <strong>Duomo fiorentino<\/strong>.<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dal lato oscuro di Firenze del passato ad un presente ancora pi\u00f9 buio<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Anche il XX secolo \u00e8 stato teatro di eventi terribili. Negli anni \u201880 a Firenze agisce quello che \u00e8 stato il primo omicida seriale in Italia, conosciuto come \u201c<strong><em>il mostro di Firenze<\/em><\/strong>\u201d.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Nel 1993 un vile <strong>attacco mafioso<\/strong> accanto alla <a href=\"\/it\/tours\/tour-guidato-uffizi-senza-stress\/\"><strong>Galleria degli Uffizi<\/strong><\/a> sconvolse il paese.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Storie tristi, vicine a noi nel tempo e nello spazio, testimoniano questo aspetto meno conosciuto della culla del Rinascimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Il vostro itinerario sulle tracce del lato oscuro di Firenze termina in <strong>piazza Signoria<\/strong>, il centro politico della citt\u00e0, scenario d\u2019arte cos\u00ec come di episodi sanguinosi del passato e del presente.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una passeggiata di due ore, in compagnia di una guida esperta, per portarvi indietro nel tempo, nei momenti pi\u00f9 cupi del Medioevo e del Rinascimento. Visiterete i luoghi principali di Firenze, da piazza Pitti a piazza della Signoria, e gli angoli meno conosciuti. Scoprirete come anche il presente abbia purtroppo molte storie tristi da raccontare.<\/p>\n","protected":false},"author":1,"featured_media":1555,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"tours_category":[],"tours_tag":[],"class_list":["post-2242","tours","type-tours","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lato oscuro di Firenze, tour della citt\u00e0 misteriosa - FloE Firenze<\/title>\n<meta name=\"description\" content=\"Una passeggiata nel lato oscuro di Firenze del Medioevo e del Rinascimento. Visiterete i luoghi principali e gli angoli meno conosciuti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/florencelocalguides.com\/it\/tours\/tour-firenze-misteriosa-ed-intrigante\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lato oscuro di Firenze, tour della citt\u00e0 misteriosa - FloE Firenze\" \/>\n<meta property=\"og:description\" content=\"Una passeggiata nel lato oscuro di Firenze del Medioevo e del Rinascimento. Visiterete i luoghi principali e gli angoli meno conosciuti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/florencelocalguides.com\/it\/tours\/tour-firenze-misteriosa-ed-intrigante\/\" \/>\n<meta property=\"og:site_name\" content=\"Florence Local Experts\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-19T12:41:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/florencelocalguides.com\/wp-content\/uploads\/dark-tour\/psp5435.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lato oscuro di Firenze, tour della citt\u00e0 misteriosa - FloE Firenze","description":"Una passeggiata nel lato oscuro di Firenze del Medioevo e del Rinascimento. Visiterete i luoghi principali e gli angoli meno conosciuti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/florencelocalguides.com\/it\/tours\/tour-firenze-misteriosa-ed-intrigante\/","og_locale":"it_IT","og_type":"article","og_title":"Lato oscuro di Firenze, tour della citt\u00e0 misteriosa - FloE Firenze","og_description":"Una passeggiata nel lato oscuro di Firenze del Medioevo e del Rinascimento. Visiterete i luoghi principali e gli angoli meno conosciuti.","og_url":"https:\/\/florencelocalguides.com\/it\/tours\/tour-firenze-misteriosa-ed-intrigante\/","og_site_name":"Florence Local Experts","article_modified_time":"2024-03-19T12:41:36+00:00","og_image":[{"width":1920,"height":1278,"url":"https:\/\/florencelocalguides.com\/wp-content\/uploads\/dark-tour\/psp5435.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/florencelocalguides.com\/it\/tours\/tour-firenze-misteriosa-ed-intrigante\/","url":"https:\/\/florencelocalguides.com\/it\/tours\/tour-firenze-misteriosa-ed-intrigante\/","name":"Lato oscuro di Firenze, tour della citt\u00e0 misteriosa - FloE Firenze","isPartOf":{"@id":"https:\/\/florencelocalguides.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/florencelocalguides.com\/it\/tours\/tour-firenze-misteriosa-ed-intrigante\/#primaryimage"},"image":{"@id":"https:\/\/florencelocalguides.com\/it\/tours\/tour-firenze-misteriosa-ed-intrigante\/#primaryimage"},"thumbnailUrl":"https:\/\/florencelocalguides.com\/wp-content\/uploads\/dark-tour\/psp5435.jpg","datePublished":"2023-12-07T15:35:20+00:00","dateModified":"2024-03-19T12:41:36+00:00","description":"Una passeggiata nel lato oscuro di Firenze del Medioevo e del Rinascimento. Visiterete i luoghi principali e gli angoli meno conosciuti.","breadcrumb":{"@id":"https:\/\/florencelocalguides.com\/it\/tours\/tour-firenze-misteriosa-ed-intrigante\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/florencelocalguides.com\/it\/tours\/tour-firenze-misteriosa-ed-intrigante\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/florencelocalguides.com\/it\/tours\/tour-firenze-misteriosa-ed-intrigante\/#primaryimage","url":"https:\/\/florencelocalguides.com\/wp-content\/uploads\/dark-tour\/psp5435.jpg","contentUrl":"https:\/\/florencelocalguides.com\/wp-content\/uploads\/dark-tour\/psp5435.jpg","width":1920,"height":1278},{"@type":"BreadcrumbList","@id":"https:\/\/florencelocalguides.com\/it\/tours\/tour-firenze-misteriosa-ed-intrigante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/florencelocalguides.com\/it\/"},{"@type":"ListItem","position":2,"name":"Tours","item":"https:\/\/florencelocalguides.com\/it\/tours\/"},{"@type":"ListItem","position":3,"name":"Il lato oscuro di Firenze: una passeggiata misteriosa ed intrigante"}]},{"@type":"WebSite","@id":"https:\/\/florencelocalguides.com\/it\/#website","url":"https:\/\/florencelocalguides.com\/it\/","name":"Florence Local Experts","description":"","publisher":{"@id":"https:\/\/florencelocalguides.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/florencelocalguides.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/florencelocalguides.com\/it\/#organization","name":"Florence Local Experts","url":"https:\/\/florencelocalguides.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/florencelocalguides.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/florencelocalguides.com\/wp-content\/uploads\/logo\/logo-floe-ok.svg","contentUrl":"https:\/\/florencelocalguides.com\/wp-content\/uploads\/logo\/logo-floe-ok.svg","caption":"Florence Local Experts"},"image":{"@id":"https:\/\/florencelocalguides.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/tours\/2242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/tours"}],"about":[{"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/types\/tours"}],"author":[{"embeddable":true,"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/comments?post=2242"}],"version-history":[{"count":9,"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/tours\/2242\/revisions"}],"predecessor-version":[{"id":3263,"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/tours\/2242\/revisions\/3263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/media\/1555"}],"wp:attachment":[{"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/media?parent=2242"}],"wp:term":[{"taxonomy":"tours_category","embeddable":true,"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/tours_category?post=2242"},{"taxonomy":"tours_tag","embeddable":true,"href":"https:\/\/florencelocalguides.com\/it\/wp-json\/wp\/v2\/tours_tag?post=2242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}